{"id":2364,"date":"2025-11-17T02:14:36","date_gmt":"2025-11-17T02:14:36","guid":{"rendered":"https:\/\/socialport.com.br\/?page_id=2364"},"modified":"2025-12-23T18:51:35","modified_gmt":"2025-12-23T18:51:35","slug":"entrevistas","status":"publish","type":"page","link":"https:\/\/socialport.com.br\/en\/entrevistas\/","title":{"rendered":"Entrevistas"},"content":{"rendered":"<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div style=\"height:117px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Entrevistas<\/h2>\n\n\n\n<div style=\"height:6px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div>\n\n\n<div  class=\"gutenverse guten-postblock postblock-type-1 guten-pagination-scrollload break-point-tablet post-element guten-0AdODI\"  data-id=\"guten-0AdODI\" data-settings=\"{&quot;numberPost&quot;:&quot;20&quot;,&quot;includeCategory&quot;:[{&quot;label&quot;:&quot;Entrevistas&quot;,&quot;value&quot;:33}],&quot;categoryEnabled&quot;:false,&quot;paginationMode&quot;:&quot;scrollload&quot;,&quot;paginationNumberPost&quot;:&quot;20&quot;,&quot;inheritQuery&quot;:true,&quot;postType&quot;:&quot;post&quot;,&quot;postOffset&quot;:0,&quot;includePost&quot;:[],&quot;excludePost&quot;:[],&quot;excludeCategory&quot;:[],&quot;includeAuthor&quot;:[],&quot;includeTag&quot;:[],&quot;excludeTag&quot;:[],&quot;htmlTag&quot;:&quot;h3&quot;,&quot;categoryPosition&quot;:&quot;center&quot;,&quot;excerptEnabled&quot;:true,&quot;excerptLength&quot;:20,&quot;excerptMore&quot;:&quot;...&quot;,&quot;readmoreEnabled&quot;:true,&quot;readmoreIcon&quot;:&quot;fas fa-arrow-right&quot;,&quot;readmoreIconPosition&quot;:&quot;after&quot;,&quot;readmoreText&quot;:&quot;Read More&quot;,&quot;commentEnabled&quot;:false,&quot;commentIcon&quot;:&quot;fas fa-comment&quot;,&quot;commentIconPosition&quot;:&quot;before&quot;,&quot;metaEnabled&quot;:true,&quot;metaAuthorEnabled&quot;:true,&quot;metaAuthorByText&quot;:&quot;by&quot;,&quot;metaAuthorIcon&quot;:&quot;fas fa-user&quot;,&quot;metaAuthorIconPosition&quot;:&quot;before&quot;,&quot;metaDateEnabled&quot;:true,&quot;metaDateType&quot;:&quot;published&quot;,&quot;metaDateFormat&quot;:&quot;default&quot;,&quot;metaDateFormatCustom&quot;:&quot;&quot;,&quot;metaDateIcon&quot;:&quot;fas fa-clock&quot;,&quot;metaDateIconPosition&quot;:&quot;before&quot;,&quot;postblockType&quot;:&quot;type-1&quot;,&quot;paginationLoadmoreText&quot;:&quot;Load More&quot;,&quot;paginationLoadingText&quot;:&quot;Loading...&quot;,&quot;paginationScrollLimit&quot;:0,&quot;paginationIcon&quot;:&quot;&quot;,&quot;paginationIconPosition&quot;:&quot;before&quot;,&quot;paged&quot;:1,&quot;class&quot;:null}\"><div class=\"guten-block-container\">\n            <div class=\"guten-posts guten-ajax-flag\">\n            <article class=\"guten-post post-3094 post type-post status-publish format-standard has-post-thumbnail hentry category-entrevistas\">\n                    <div class=\"guten-thumb\"><a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/o-senador-hamilton-mourao-acredita-que-a-pec-do-futuro-so-ira-destravar-em-2027\/\"><div class=\"thumbnail-container\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"602\" height=\"398\" src=\"https:\/\/socialport.com.br\/wp-content\/uploads\/2026\/08\/image-1.jpeg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/socialport.com.br\/wp-content\/uploads\/2026\/08\/image-1.jpeg 602w, https:\/\/socialport.com.br\/wp-content\/uploads\/2026\/08\/image-1-300x198.jpeg 300w, https:\/\/socialport.com.br\/wp-content\/uploads\/2026\/08\/image-1-18x12.jpeg 18w\" sizes=\"auto, 100vw\" \/>\n\t\t\t<div class=\"guten-overlay\"><\/div>\n        <\/div><\/a><\/div>\n                    <div class=\"guten-postblock-content\"><h3 class=\"guten-post-title\"><a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/o-senador-hamilton-mourao-acredita-que-a-pec-do-futuro-so-ira-destravar-em-2027\/\">O senador Hamilton Mour\u00e3o acredita que a PEC do \u201cfuturo\u201d s\u00f3 ir\u00e1 destravar em 2027<\/a><\/h3>\n                <div class=\"guten-post-meta\"><div class=\"guten-meta-author icon-position-before\"><i aria-hidden=\"true\" class=\"fas fa-user\"><\/i><span class=\"by\">by<\/span> <a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/author\/claudinei\/\">Claudinei Abreu<\/a><\/div><div class=\"guten-meta-date icon-position-before\"><i aria-hidden=\"true\" class=\"fas fa-clock\"><\/i>19\/08\/2026<\/div><\/div><div class=\"guten-post-excerpt\"><p>O senador Hamilton Mour\u00e3o acredita que a PEC do \u201cfuturo\u201d s\u00f3 ir\u00e1 destravar em 2027 Proposta de Emenda \u00e0 Constitui\u00e7\u00e3o&#8230;<\/p><\/div>\n            <div class=\"guten-post-meta-bottom\">\n                <div class=\"guten-meta-readmore icon-position-after\">\n                <a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/o-senador-hamilton-mourao-acredita-que-a-pec-do-futuro-so-ira-destravar-em-2027\/\" class=\"guten-readmore\">Read More<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i><\/a>\n            <\/div>\n            <\/div><\/div>\n                <\/article><article class=\"guten-post post-3084 post type-post status-publish format-standard has-post-thumbnail hentry category-entrevistas\">\n                    <div class=\"guten-thumb\"><a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/capacitacao-na-aeronautica-com-a-socialport-mudou-a-mentalidade-dos-funcionarios-da-forca-aerea-destacou-thiago-santos-coordenador-no-laboratorio-de-simulacao-e-cenarios-do-poder-aeroespacial-da-aer\/\"><div class=\"thumbnail-container\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"602\" height=\"338\" src=\"https:\/\/socialport.com.br\/wp-content\/uploads\/2026\/08\/image.jpeg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/socialport.com.br\/wp-content\/uploads\/2026\/08\/image.jpeg 602w, https:\/\/socialport.com.br\/wp-content\/uploads\/2026\/08\/image-300x168.jpeg 300w, https:\/\/socialport.com.br\/wp-content\/uploads\/2026\/08\/image-18x10.jpeg 18w\" sizes=\"auto, 100vw\" \/>\n\t\t\t<div class=\"guten-overlay\"><\/div>\n        <\/div><\/a><\/div>\n                    <div class=\"guten-postblock-content\"><h3 class=\"guten-post-title\"><a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/capacitacao-na-aeronautica-com-a-socialport-mudou-a-mentalidade-dos-funcionarios-da-forca-aerea-destacou-thiago-santos-coordenador-no-laboratorio-de-simulacao-e-cenarios-do-poder-aeroespacial-da-aer\/\">Capacita\u00e7\u00e3o na Aeron\u00e1utica com a SocialPort mudou a mentalidade dos funcion\u00e1rios da For\u00e7a A\u00e9rea, destacou Thiago Santos, coordenador no Laborat\u00f3rio de Simula\u00e7\u00e3o e Cen\u00e1rios do Poder Aeroespacial da Aeron\u00e1utica<\/a><\/h3>\n                <div class=\"guten-post-meta\"><div class=\"guten-meta-author icon-position-before\"><i aria-hidden=\"true\" class=\"fas fa-user\"><\/i><span class=\"by\">by<\/span> <a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/author\/claudinei\/\">Claudinei Abreu<\/a><\/div><div class=\"guten-meta-date icon-position-before\"><i aria-hidden=\"true\" class=\"fas fa-clock\"><\/i>12\/08\/2026<\/div><\/div><div class=\"guten-post-excerpt\"><p>Capacita\u00e7\u00e3o na Aeron\u00e1utica com a SocialPort mudou a mentalidade dos funcion\u00e1rios da For\u00e7a A\u00e9rea, destacou Thiago Santos, coordenador no Laborat\u00f3rio&#8230;<\/p><\/div>\n            <div class=\"guten-post-meta-bottom\">\n                <div class=\"guten-meta-readmore icon-position-after\">\n                <a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/capacitacao-na-aeronautica-com-a-socialport-mudou-a-mentalidade-dos-funcionarios-da-forca-aerea-destacou-thiago-santos-coordenador-no-laboratorio-de-simulacao-e-cenarios-do-poder-aeroespacial-da-aer\/\" class=\"guten-readmore\">Read More<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i><\/a>\n            <\/div>\n            <\/div><\/div>\n                <\/article><article class=\"guten-post post-2990 post type-post status-publish format-standard has-post-thumbnail hentry category-entrevistas\">\n                    <div class=\"guten-thumb\"><a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/ricardo-croce-colaborador-da-socialport-e-expert-na-matriz-de-eisenhower-e-inteligencia-estrategica-destacou-a-ferramenta-como-sendo-pratica\/\"><div class=\"thumbnail-container\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"2283\" height=\"1280\" src=\"https:\/\/socialport.com.br\/wp-content\/uploads\/2026\/06\/Gemini_Generated_Image_8tsx8a8tsx8a8tsx-scaled-e1781630075671.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/socialport.com.br\/wp-content\/uploads\/2026\/06\/Gemini_Generated_Image_8tsx8a8tsx8a8tsx-scaled-e1781630075671.png 2283w, https:\/\/socialport.com.br\/wp-content\/uploads\/2026\/06\/Gemini_Generated_Image_8tsx8a8tsx8a8tsx-scaled-e1781630075671-300x168.png 300w, https:\/\/socialport.com.br\/wp-content\/uploads\/2026\/06\/Gemini_Generated_Image_8tsx8a8tsx8a8tsx-scaled-e1781630075671-1024x574.png 1024w, https:\/\/socialport.com.br\/wp-content\/uploads\/2026\/06\/Gemini_Generated_Image_8tsx8a8tsx8a8tsx-scaled-e1781630075671-768x431.png 768w, https:\/\/socialport.com.br\/wp-content\/uploads\/2026\/06\/Gemini_Generated_Image_8tsx8a8tsx8a8tsx-scaled-e1781630075671-1536x861.png 1536w, https:\/\/socialport.com.br\/wp-content\/uploads\/2026\/06\/Gemini_Generated_Image_8tsx8a8tsx8a8tsx-scaled-e1781630075671-2048x1148.png 2048w, https:\/\/socialport.com.br\/wp-content\/uploads\/2026\/06\/Gemini_Generated_Image_8tsx8a8tsx8a8tsx-scaled-e1781630075671-18x10.png 18w, https:\/\/socialport.com.br\/wp-content\/uploads\/2026\/06\/Gemini_Generated_Image_8tsx8a8tsx8a8tsx-scaled-e1781630075671-2000x1121.png 2000w\" sizes=\"auto, 100vw\" \/>\n\t\t\t<div class=\"guten-overlay\"><\/div>\n        <\/div><\/a><\/div>\n                    <div class=\"guten-postblock-content\"><h3 class=\"guten-post-title\"><a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/ricardo-croce-colaborador-da-socialport-e-expert-na-matriz-de-eisenhower-e-inteligencia-estrategica-destacou-a-ferramenta-como-sendo-pratica\/\">Ricardo Croce, colaborador da SocialPort e expert na Matriz de Eisenhower e Intelig\u00eancia estrat\u00e9gica, destacou a ferramenta como sendo \u201cpr\u00e1tica\u201d<\/a><\/h3>\n                <div class=\"guten-post-meta\"><div class=\"guten-meta-author icon-position-before\"><i aria-hidden=\"true\" class=\"fas fa-user\"><\/i><span class=\"by\">by<\/span> <a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/author\/claudinei\/\">Claudinei Abreu<\/a><\/div><div class=\"guten-meta-date icon-position-before\"><i aria-hidden=\"true\" class=\"fas fa-clock\"><\/i>18\/06\/2026<\/div><\/div><div class=\"guten-post-excerpt\"><p>Ricardo Croce, colaborador da SocialPort e expert na Matriz de Eisenhower e Intelig\u00eancia estrat\u00e9gica, destacou a ferramenta como sendo \u201cpr\u00e1tica\u201d&#8230;<\/p><\/div>\n            <div class=\"guten-post-meta-bottom\">\n                <div class=\"guten-meta-readmore icon-position-after\">\n                <a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/ricardo-croce-colaborador-da-socialport-e-expert-na-matriz-de-eisenhower-e-inteligencia-estrategica-destacou-a-ferramenta-como-sendo-pratica\/\" class=\"guten-readmore\">Read More<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i><\/a>\n            <\/div>\n            <\/div><\/div>\n                <\/article><article class=\"guten-post post-2968 post type-post status-publish format-standard has-post-thumbnail hentry category-entrevistas\">\n                    <div class=\"guten-thumb\"><a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/pedro-henrique-um-dos-fundadores-da-socialport-desempenha-um-papel-secundario-mas-de-extrema-relevancia-para-o-exito-da-empresa\/\"><div class=\"thumbnail-container\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" src=\"https:\/\/socialport.com.br\/wp-content\/uploads\/2026\/06\/Burocracia.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/socialport.com.br\/wp-content\/uploads\/2026\/06\/Burocracia.jpg 1000w, https:\/\/socialport.com.br\/wp-content\/uploads\/2026\/06\/Burocracia-300x200.jpg 300w, https:\/\/socialport.com.br\/wp-content\/uploads\/2026\/06\/Burocracia-768x512.jpg 768w, https:\/\/socialport.com.br\/wp-content\/uploads\/2026\/06\/Burocracia-18x12.jpg 18w\" sizes=\"auto, 100vw\" \/>\n\t\t\t<div class=\"guten-overlay\"><\/div>\n        <\/div><\/a><\/div>\n                    <div class=\"guten-postblock-content\"><h3 class=\"guten-post-title\"><a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/pedro-henrique-um-dos-fundadores-da-socialport-desempenha-um-papel-secundario-mas-de-extrema-relevancia-para-o-exito-da-empresa\/\">Pedro Henrique, um dos fundadores da SocialPort, desempenha um papel secund\u00e1rio, mas de extrema relev\u00e2ncia para o \u00eaxito da empresa<\/a><\/h3>\n                <div class=\"guten-post-meta\"><div class=\"guten-meta-author icon-position-before\"><i aria-hidden=\"true\" class=\"fas fa-user\"><\/i><span class=\"by\">by<\/span> <a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/author\/claudinei\/\">Claudinei Abreu<\/a><\/div><div class=\"guten-meta-date icon-position-before\"><i aria-hidden=\"true\" class=\"fas fa-clock\"><\/i>01\/06\/2026<\/div><\/div><div class=\"guten-post-excerpt\"><p>Pedro Henrique, um dos fundadores da SocialPort, desempenha um papel secund\u00e1rio, mas de extrema relev\u00e2ncia para o \u00eaxito da empresa&#8230;<\/p><\/div>\n            <div class=\"guten-post-meta-bottom\">\n                <div class=\"guten-meta-readmore icon-position-after\">\n                <a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/pedro-henrique-um-dos-fundadores-da-socialport-desempenha-um-papel-secundario-mas-de-extrema-relevancia-para-o-exito-da-empresa\/\" class=\"guten-readmore\">Read More<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i><\/a>\n            <\/div>\n            <\/div><\/div>\n                <\/article><article class=\"guten-post post-2956 post type-post status-publish format-standard has-post-thumbnail hentry category-entrevistas\">\n                    <div class=\"guten-thumb\"><a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/a-estudante-de-biblioteconomia-e-estagiaria-da-sociaport-rafaella-sales-explica-sobre-o-projeto-da-biblioteca-virtual-e-destaca-as-experiencias-conquistadas-atraves-da-empresa\/\"><div class=\"thumbnail-container\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"661\" height=\"360\" src=\"https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/06\/futurismo.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/06\/futurismo.jpg 661w, https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/06\/futurismo-300x163.jpg 300w, https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/06\/futurismo-18x10.jpg 18w\" sizes=\"auto, 100vw\" \/>\n\t\t\t<div class=\"guten-overlay\"><\/div>\n        <\/div><\/a><\/div>\n                    <div class=\"guten-postblock-content\"><h3 class=\"guten-post-title\"><a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/a-estudante-de-biblioteconomia-e-estagiaria-da-sociaport-rafaella-sales-explica-sobre-o-projeto-da-biblioteca-virtual-e-destaca-as-experiencias-conquistadas-atraves-da-empresa\/\">A estudante de Biblioteconomia e estagi\u00e1ria da SociaPort, Rafaella Sales, explica sobre o projeto da \u201cbiblioteca virtual\u201d e destaca as experi\u00eancias conquistadas atrav\u00e9s da empresa<\/a><\/h3>\n                <div class=\"guten-post-meta\"><div class=\"guten-meta-author icon-position-before\"><i aria-hidden=\"true\" class=\"fas fa-user\"><\/i><span class=\"by\">by<\/span> <a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/author\/claudinei\/\">Claudinei Abreu<\/a><\/div><div class=\"guten-meta-date icon-position-before\"><i aria-hidden=\"true\" class=\"fas fa-clock\"><\/i>21\/05\/2026<\/div><\/div><div class=\"guten-post-excerpt\"><p>A estudante de Biblioteconomia e estagi\u00e1ria da SociaPort, Rafaella Sales, explica sobre o projeto da \u201cbiblioteca virtual\u201d e destaca as&#8230;<\/p><\/div>\n            <div class=\"guten-post-meta-bottom\">\n                <div class=\"guten-meta-readmore icon-position-after\">\n                <a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/a-estudante-de-biblioteconomia-e-estagiaria-da-sociaport-rafaella-sales-explica-sobre-o-projeto-da-biblioteca-virtual-e-destaca-as-experiencias-conquistadas-atraves-da-empresa\/\" class=\"guten-readmore\">Read More<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i><\/a>\n            <\/div>\n            <\/div><\/div>\n                <\/article><article class=\"guten-post post-2944 post type-post status-publish format-standard has-post-thumbnail hentry category-entrevistas\">\n                    <div class=\"guten-thumb\"><a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/elaine-marcial-socia-fundadora-da-socialport-explica-nome-da-empresa\/\"><div class=\"thumbnail-container\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"661\" height=\"360\" src=\"https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/06\/futurismo.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/06\/futurismo.jpg 661w, https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/06\/futurismo-300x163.jpg 300w, https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/06\/futurismo-18x10.jpg 18w\" sizes=\"auto, 100vw\" \/>\n\t\t\t<div class=\"guten-overlay\"><\/div>\n        <\/div><\/a><\/div>\n                    <div class=\"guten-postblock-content\"><h3 class=\"guten-post-title\"><a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/elaine-marcial-socia-fundadora-da-socialport-explica-nome-da-empresa\/\">Elaine Marcial, s\u00f3cia-fundadora da SocialPort explica nome da empresa<\/a><\/h3>\n                <div class=\"guten-post-meta\"><div class=\"guten-meta-author icon-position-before\"><i aria-hidden=\"true\" class=\"fas fa-user\"><\/i><span class=\"by\">by<\/span> <a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/author\/claudinei\/\">Claudinei Abreu<\/a><\/div><div class=\"guten-meta-date icon-position-before\"><i aria-hidden=\"true\" class=\"fas fa-clock\"><\/i>06\/05\/2026<\/div><\/div><div class=\"guten-post-excerpt\"><p>Elaine Marcial, s\u00f3cia-fundadora da SocialPort explica nome da empresa A SocialPort \u00e9 uma das empresas de foresight mais influentes do&#8230;<\/p><\/div>\n            <div class=\"guten-post-meta-bottom\">\n                <div class=\"guten-meta-readmore icon-position-after\">\n                <a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/elaine-marcial-socia-fundadora-da-socialport-explica-nome-da-empresa\/\" class=\"guten-readmore\">Read More<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i><\/a>\n            <\/div>\n            <\/div><\/div>\n                <\/article><article class=\"guten-post post-2935 post type-post status-publish format-standard has-post-thumbnail hentry category-entrevistas\">\n                    <div class=\"guten-thumb\"><a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/o-internacionalista-vinicius-rasga-elogios-a-socialport-enterprises-e-destaca-sua-usabilidade-e-confiabilidade\/\"><div class=\"thumbnail-container\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"661\" height=\"360\" src=\"https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/06\/futurismo.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/06\/futurismo.jpg 661w, https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/06\/futurismo-300x163.jpg 300w, https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/06\/futurismo-18x10.jpg 18w\" sizes=\"auto, 100vw\" \/>\n\t\t\t<div class=\"guten-overlay\"><\/div>\n        <\/div><\/a><\/div>\n                    <div class=\"guten-postblock-content\"><h3 class=\"guten-post-title\"><a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/o-internacionalista-vinicius-rasga-elogios-a-socialport-enterprises-e-destaca-sua-usabilidade-e-confiabilidade\/\">O internacionalista Vinicius rasga elogios a SocialPort Enterprises e destaca sua usabilidade e confiabilidade<\/a><\/h3>\n                <div class=\"guten-post-meta\"><div class=\"guten-meta-author icon-position-before\"><i aria-hidden=\"true\" class=\"fas fa-user\"><\/i><span class=\"by\">by<\/span> <a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/author\/claudinei\/\">Claudinei Abreu<\/a><\/div><div class=\"guten-meta-date icon-position-before\"><i aria-hidden=\"true\" class=\"fas fa-clock\"><\/i>24\/04\/2026<\/div><\/div><div class=\"guten-post-excerpt\"><p>O internacionalista Vin\u00edcius Janick rasga elogios a SocialPort Enterprises e destaca sua usabilidade e confiabilidade Em rela\u00e7\u00e3o ao seu projeto&#8230;<\/p><\/div>\n            <div class=\"guten-post-meta-bottom\">\n                <div class=\"guten-meta-readmore icon-position-after\">\n                <a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/o-internacionalista-vinicius-rasga-elogios-a-socialport-enterprises-e-destaca-sua-usabilidade-e-confiabilidade\/\" class=\"guten-readmore\">Read More<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i><\/a>\n            <\/div>\n            <\/div><\/div>\n                <\/article><article class=\"guten-post post-2919 post type-post status-publish format-standard has-post-thumbnail hentry category-entrevistas\">\n                    <div class=\"guten-thumb\"><a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/elaine-nobrega-enxerga-a-tomada-de-decisao-de-maneira-mais-facil-apos-a-capacitacao-da-professora-e-socia-da-socialport-elaine-marcial-no-stj\/\"><div class=\"thumbnail-container\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"602\" height=\"326\" src=\"https:\/\/socialport.com.br\/wp-content\/uploads\/2026\/04\/image.jpeg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/socialport.com.br\/wp-content\/uploads\/2026\/04\/image.jpeg 602w, https:\/\/socialport.com.br\/wp-content\/uploads\/2026\/04\/image-300x162.jpeg 300w, https:\/\/socialport.com.br\/wp-content\/uploads\/2026\/04\/image-18x10.jpeg 18w\" sizes=\"auto, 100vw\" \/>\n\t\t\t<div class=\"guten-overlay\"><\/div>\n        <\/div><\/a><\/div>\n                    <div class=\"guten-postblock-content\"><h3 class=\"guten-post-title\"><a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/elaine-nobrega-enxerga-a-tomada-de-decisao-de-maneira-mais-facil-apos-a-capacitacao-da-professora-e-socia-da-socialport-elaine-marcial-no-stj\/\">Elaine N\u00f3brega enxerga a tomada de decis\u00e3o de maneira mais &#8220;f\u00e1cil&#8221; ap\u00f3s a capacita\u00e7\u00e3o da Professora e s\u00f3cia da SocialPort, Elaine Marcial no STJ<\/a><\/h3>\n                <div class=\"guten-post-meta\"><div class=\"guten-meta-author icon-position-before\"><i aria-hidden=\"true\" class=\"fas fa-user\"><\/i><span class=\"by\">by<\/span> <a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/author\/claudinei\/\">Claudinei Abreu<\/a><\/div><div class=\"guten-meta-date icon-position-before\"><i aria-hidden=\"true\" class=\"fas fa-clock\"><\/i>07\/04\/2026<\/div><\/div><div class=\"guten-post-excerpt\"><p>Elaine N\u00f3brega enxerga a tomada de decis\u00e3o de maneira mais &#8220;f\u00e1cil&#8221; ap\u00f3s a capacita\u00e7\u00e3o da Professora e s\u00f3cia da SocialPort,&#8230;<\/p><\/div>\n            <div class=\"guten-post-meta-bottom\">\n                <div class=\"guten-meta-readmore icon-position-after\">\n                <a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/elaine-nobrega-enxerga-a-tomada-de-decisao-de-maneira-mais-facil-apos-a-capacitacao-da-professora-e-socia-da-socialport-elaine-marcial-no-stj\/\" class=\"guten-readmore\">Read More<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i><\/a>\n            <\/div>\n            <\/div><\/div>\n                <\/article><article class=\"guten-post post-2825 post type-post status-publish format-standard has-post-thumbnail hentry category-entrevistas\">\n                    <div class=\"guten-thumb\"><a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/a-autora-do-livro-fazer-boas-escolhas-e-um-estilo-de-vida-acredita-que-uma-organizacao-necessita-ser-madura-para-implementar-a-ahp\/\"><div class=\"thumbnail-container\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"582\" height=\"416\" src=\"https:\/\/socialport.com.br\/wp-content\/uploads\/2026\/03\/image.jpeg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/socialport.com.br\/wp-content\/uploads\/2026\/03\/image.jpeg 582w, https:\/\/socialport.com.br\/wp-content\/uploads\/2026\/03\/image-300x214.jpeg 300w, https:\/\/socialport.com.br\/wp-content\/uploads\/2026\/03\/image-18x12.jpeg 18w\" sizes=\"auto, 100vw\" \/>\n\t\t\t<div class=\"guten-overlay\"><\/div>\n        <\/div><\/a><\/div>\n                    <div class=\"guten-postblock-content\"><h3 class=\"guten-post-title\"><a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/a-autora-do-livro-fazer-boas-escolhas-e-um-estilo-de-vida-acredita-que-uma-organizacao-necessita-ser-madura-para-implementar-a-ahp\/\">A autora do livro, &#8220;Fazer boas escolhas \u00e9 um estilo de vida&#8221;, acredita que uma organiza\u00e7\u00e3o necessita ser &#8220;madura&#8221; para implementar a AHP<\/a><\/h3>\n                <div class=\"guten-post-meta\"><div class=\"guten-meta-author icon-position-before\"><i aria-hidden=\"true\" class=\"fas fa-user\"><\/i><span class=\"by\">by<\/span> <a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/author\/claudinei\/\">Claudinei Abreu<\/a><\/div><div class=\"guten-meta-date icon-position-before\"><i aria-hidden=\"true\" class=\"fas fa-clock\"><\/i>23\/03\/2026<\/div><\/div><div class=\"guten-post-excerpt\"><p>A autora do livro, &#8220;Fazer boas escolhas \u00e9 um estilo de vida&#8221;, acredita que uma organiza\u00e7\u00e3o necessita ser &#8220;madura&#8221; para&#8230;<\/p><\/div>\n            <div class=\"guten-post-meta-bottom\">\n                <div class=\"guten-meta-readmore icon-position-after\">\n                <a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/a-autora-do-livro-fazer-boas-escolhas-e-um-estilo-de-vida-acredita-que-uma-organizacao-necessita-ser-madura-para-implementar-a-ahp\/\" class=\"guten-readmore\">Read More<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i><\/a>\n            <\/div>\n            <\/div><\/div>\n                <\/article><article class=\"guten-post post-2470 post type-post status-publish format-standard has-post-thumbnail hentry category-entrevistas\">\n                    <div class=\"guten-thumb\"><a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/elimine-o-achismo-estrategico-como-a-socialport-enterprise-otimiza-a-analise-de-motricidade-e-dependencia\/\"><div class=\"thumbnail-container\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"602\" height=\"401\" src=\"https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/12\/image.jpeg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/12\/image.jpeg 602w, https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/12\/image-300x200.jpeg 300w, https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/12\/image-18x12.jpeg 18w\" sizes=\"auto, 100vw\" \/>\n\t\t\t<div class=\"guten-overlay\"><\/div>\n        <\/div><\/a><\/div>\n                    <div class=\"guten-postblock-content\"><h3 class=\"guten-post-title\"><a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/elimine-o-achismo-estrategico-como-a-socialport-enterprise-otimiza-a-analise-de-motricidade-e-dependencia\/\">Elimine o &#8220;achismo&#8221; estrat\u00e9gico: Como a SocialPort Enterprise otimiza a an\u00e1lise de Motricidade e Depend\u00eancia<\/a><\/h3>\n                <div class=\"guten-post-meta\"><div class=\"guten-meta-author icon-position-before\"><i aria-hidden=\"true\" class=\"fas fa-user\"><\/i><span class=\"by\">by<\/span> <a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/author\/claudinei\/\">Claudinei Abreu<\/a><\/div><div class=\"guten-meta-date icon-position-before\"><i aria-hidden=\"true\" class=\"fas fa-clock\"><\/i>10\/12\/2025<\/div><\/div><div class=\"guten-post-excerpt\"><p>Elimine o &#8220;achismo&#8221; estrat\u00e9gico: Como a SocialPort Enterprise otimiza a an\u00e1lise de Motricidade e Depend\u00eancia A tomada de decis\u00e3o estrat\u00e9gica&#8230;<\/p><\/div>\n            <div class=\"guten-post-meta-bottom\">\n                <div class=\"guten-meta-readmore icon-position-after\">\n                <a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/elimine-o-achismo-estrategico-como-a-socialport-enterprise-otimiza-a-analise-de-motricidade-e-dependencia\/\" class=\"guten-readmore\">Read More<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i><\/a>\n            <\/div>\n            <\/div><\/div>\n                <\/article><article class=\"guten-post post-2348 post type-post status-publish format-standard has-post-thumbnail hentry category-entrevistas category-noticias\">\n                    <div class=\"guten-thumb\"><a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/marcello-pio-revela-que-uma-das-maiores-vantagens-do-ranking-de-incertezas-criticas-e-a-eliminacao-de-vieses\/\"><div class=\"thumbnail-container\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"602\" height=\"401\" src=\"https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/10\/image.jpeg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/10\/image.jpeg 602w, https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/10\/image-300x200.jpeg 300w, https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/10\/image-18x12.jpeg 18w\" sizes=\"auto, 100vw\" \/>\n\t\t\t<div class=\"guten-overlay\"><\/div>\n        <\/div><\/a><\/div>\n                    <div class=\"guten-postblock-content\"><h3 class=\"guten-post-title\"><a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/marcello-pio-revela-que-uma-das-maiores-vantagens-do-ranking-de-incertezas-criticas-e-a-eliminacao-de-vieses\/\">Marcello Pio revela que uma das maiores vantagens do Ranking de Incertezas Cr\u00edticas \u00e9 a elimina\u00e7\u00e3o de &#8220;vieses&#8221;<\/a><\/h3>\n                <div class=\"guten-post-meta\"><div class=\"guten-meta-author icon-position-before\"><i aria-hidden=\"true\" class=\"fas fa-user\"><\/i><span class=\"by\">by<\/span> <a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/author\/claudinei\/\">Claudinei Abreu<\/a><\/div><div class=\"guten-meta-date icon-position-before\"><i aria-hidden=\"true\" class=\"fas fa-clock\"><\/i>31\/10\/2025<\/div><\/div><div class=\"guten-post-excerpt\"><p>Marcello Pio revela que uma das maiores vantagens do Ranking de Incertezas Cr\u00edticas \u00e9 a elimina\u00e7\u00e3o de &#8220;vieses&#8221; Marcello complementa&#8230;<\/p><\/div>\n            <div class=\"guten-post-meta-bottom\">\n                <div class=\"guten-meta-readmore icon-position-after\">\n                <a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/marcello-pio-revela-que-uma-das-maiores-vantagens-do-ranking-de-incertezas-criticas-e-a-eliminacao-de-vieses\/\" class=\"guten-readmore\">Read More<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i><\/a>\n            <\/div>\n            <\/div><\/div>\n                <\/article><article class=\"guten-post post-2256 post type-post status-publish format-standard has-post-thumbnail hentry category-entrevistas category-noticias\">\n                    <div class=\"guten-thumb\"><a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/desmatamento-ilegal-responde-pela-maior-parte-do-efeito-estufa-atribuido-ao-agro-diz-jose-manuel-da-embrapa\/\"><div class=\"thumbnail-container\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/09\/Agro-4.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/09\/Agro-4.jpg 1024w, https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/09\/Agro-4-300x150.jpg 300w, https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/09\/Agro-4-768x384.jpg 768w, https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/09\/Agro-4-18x9.jpg 18w\" sizes=\"auto, 100vw\" \/>\n\t\t\t<div class=\"guten-overlay\"><\/div>\n        <\/div><\/a><\/div>\n                    <div class=\"guten-postblock-content\"><h3 class=\"guten-post-title\"><a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/desmatamento-ilegal-responde-pela-maior-parte-do-efeito-estufa-atribuido-ao-agro-diz-jose-manuel-da-embrapa\/\">\u201cDesmatamento ilegal responde pela maior parte do efeito estufa atribu\u00eddo ao agro\u201d, diz Jos\u00e9 Manuel da Embrapa<\/a><\/h3>\n                <div class=\"guten-post-meta\"><div class=\"guten-meta-author icon-position-before\"><i aria-hidden=\"true\" class=\"fas fa-user\"><\/i><span class=\"by\">by<\/span> <a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/author\/claudinei\/\">Claudinei Abreu<\/a><\/div><div class=\"guten-meta-date icon-position-before\"><i aria-hidden=\"true\" class=\"fas fa-clock\"><\/i>12\/09\/2025<\/div><\/div><div class=\"guten-post-excerpt\"><p>\u201cDesmatamento ilegal responde pela maior parte do efeito estufa atribu\u00eddo ao agro\u201d, diz Jos\u00e9 Manuel da Embrapa Pesquisador tamb\u00e9m avalia&#8230;<\/p><\/div>\n            <div class=\"guten-post-meta-bottom\">\n                <div class=\"guten-meta-readmore icon-position-after\">\n                <a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/desmatamento-ilegal-responde-pela-maior-parte-do-efeito-estufa-atribuido-ao-agro-diz-jose-manuel-da-embrapa\/\" class=\"guten-readmore\">Read More<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i><\/a>\n            <\/div>\n            <\/div><\/div>\n                <\/article><article class=\"guten-post post-2219 post type-post status-publish format-standard has-post-thumbnail hentry category-entrevistas category-noticias\">\n                    <div class=\"guten-thumb\"><a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/para-whagtom-nunes-do-ibee-especialista-em-seguranca-publica-e-inevitavel-abrir-mao-de-uma-certa-privacidade-para-se-ter-seguranca\/\"><div class=\"thumbnail-container\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"627\" src=\"https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/07\/Seguranca-Publica-no-futuro-do-Brasil.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/07\/Seguranca-Publica-no-futuro-do-Brasil.jpg 1200w, https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/07\/Seguranca-Publica-no-futuro-do-Brasil-300x157.jpg 300w, https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/07\/Seguranca-Publica-no-futuro-do-Brasil-1024x535.jpg 1024w, https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/07\/Seguranca-Publica-no-futuro-do-Brasil-768x401.jpg 768w, https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/07\/Seguranca-Publica-no-futuro-do-Brasil-18x9.jpg 18w\" sizes=\"auto, 100vw\" \/>\n\t\t\t<div class=\"guten-overlay\"><\/div>\n        <\/div><\/a><\/div>\n                    <div class=\"guten-postblock-content\"><h3 class=\"guten-post-title\"><a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/para-whagtom-nunes-do-ibee-especialista-em-seguranca-publica-e-inevitavel-abrir-mao-de-uma-certa-privacidade-para-se-ter-seguranca\/\">Para Whagtom Nunes do IBEE, especialista em Seguran\u00e7a P\u00fablica, \u00e9 inevit\u00e1vel \u2018abrir m\u00e3o\u2019 de uma certa privacidade para se ter seguran\u00e7a<\/a><\/h3>\n                <div class=\"guten-post-meta\"><div class=\"guten-meta-author icon-position-before\"><i aria-hidden=\"true\" class=\"fas fa-user\"><\/i><span class=\"by\">by<\/span> <a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/author\/claudinei\/\">Claudinei Abreu<\/a><\/div><div class=\"guten-meta-date icon-position-before\"><i aria-hidden=\"true\" class=\"fas fa-clock\"><\/i>28\/07\/2025<\/div><\/div><div class=\"guten-post-excerpt\"><p>Para Whagtom Nunes do IBEE, especialista em Seguran\u00e7a P\u00fablica, \u00e9 inevit\u00e1vel \u2018abrir m\u00e3o\u2019 de uma certa privacidade para se ter&#8230;<\/p><\/div>\n            <div class=\"guten-post-meta-bottom\">\n                <div class=\"guten-meta-readmore icon-position-after\">\n                <a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/para-whagtom-nunes-do-ibee-especialista-em-seguranca-publica-e-inevitavel-abrir-mao-de-uma-certa-privacidade-para-se-ter-seguranca\/\" class=\"guten-readmore\">Read More<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i><\/a>\n            <\/div>\n            <\/div><\/div>\n                <\/article><article class=\"guten-post post-2217 post type-post status-publish format-standard has-post-thumbnail hentry category-entrevistas category-noticias\">\n                    <div class=\"guten-thumb\"><a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/para-joao-menezes-especialista-em-tics-regulamentar-o-uso-da-inteligencia-artificial-nao-e-100-eficaz\/\"><div class=\"thumbnail-container\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"661\" height=\"360\" src=\"https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/06\/futurismo.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/06\/futurismo.jpg 661w, https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/06\/futurismo-300x163.jpg 300w, https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/06\/futurismo-18x10.jpg 18w\" sizes=\"auto, 100vw\" \/>\n\t\t\t<div class=\"guten-overlay\"><\/div>\n        <\/div><\/a><\/div>\n                    <div class=\"guten-postblock-content\"><h3 class=\"guten-post-title\"><a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/para-joao-menezes-especialista-em-tics-regulamentar-o-uso-da-inteligencia-artificial-nao-e-100-eficaz\/\">Para Jo\u00e3o Menezes, especialista em TICS, regulamentar o uso da intelig\u00eancia artificial n\u00e3o \u00e9 100% eficaz<\/a><\/h3>\n                <div class=\"guten-post-meta\"><div class=\"guten-meta-author icon-position-before\"><i aria-hidden=\"true\" class=\"fas fa-user\"><\/i><span class=\"by\">by<\/span> <a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/author\/claudinei\/\">Claudinei Abreu<\/a><\/div><div class=\"guten-meta-date icon-position-before\"><i aria-hidden=\"true\" class=\"fas fa-clock\"><\/i>24\/07\/2025<\/div><\/div><div class=\"guten-post-excerpt\"><p>Para Jo\u00e3o Menezes, especialista em TICS, regulamentar o uso da intelig\u00eancia artificial n\u00e3o \u00e9 100% eficaz O especialista e signat\u00e1rio&#8230;<\/p><\/div>\n            <div class=\"guten-post-meta-bottom\">\n                <div class=\"guten-meta-readmore icon-position-after\">\n                <a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/para-joao-menezes-especialista-em-tics-regulamentar-o-uso-da-inteligencia-artificial-nao-e-100-eficaz\/\" class=\"guten-readmore\">Read More<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i><\/a>\n            <\/div>\n            <\/div><\/div>\n                <\/article><article class=\"guten-post post-1907 post type-post status-publish format-standard has-post-thumbnail hentry category-entrevistas category-noticias\">\n                    <div class=\"guten-thumb\"><a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/brasil-tem-grandes-chances-de-liderar-transicao-energetica-global-ate-2045-segundo-marcio-venicio\/\"><div class=\"thumbnail-container\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"661\" height=\"360\" src=\"https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/06\/futurismo.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/06\/futurismo.jpg 661w, https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/06\/futurismo-300x163.jpg 300w, https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/06\/futurismo-18x10.jpg 18w\" sizes=\"auto, 100vw\" \/>\n\t\t\t<div class=\"guten-overlay\"><\/div>\n        <\/div><\/a><\/div>\n                    <div class=\"guten-postblock-content\"><h3 class=\"guten-post-title\"><a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/brasil-tem-grandes-chances-de-liderar-transicao-energetica-global-ate-2045-segundo-marcio-venicio\/\">Brasil tem \u2018grandes chances\u2019 de liderar transi\u00e7\u00e3o energ\u00e9tica global at\u00e9 2045, segundo M\u00e1rcio Ven\u00edcio\u00a0<\/a><\/h3>\n                <div class=\"guten-post-meta\"><div class=\"guten-meta-author icon-position-before\"><i aria-hidden=\"true\" class=\"fas fa-user\"><\/i><span class=\"by\">by<\/span> <a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/author\/claudinei\/\">Claudinei Abreu<\/a><\/div><div class=\"guten-meta-date icon-position-before\"><i aria-hidden=\"true\" class=\"fas fa-clock\"><\/i>30\/06\/2025<\/div><\/div><div class=\"guten-post-excerpt\"><p>Brasil tem \u2018grandes chances\u2019 de liderar transi\u00e7\u00e3o energ\u00e9tica global at\u00e9 2045, segundo M\u00e1rcio Ven\u00edcio\u00a0 Brasil visto do espa\u00e7o \u00e0 noite&#8230;<\/p><\/div>\n            <div class=\"guten-post-meta-bottom\">\n                <div class=\"guten-meta-readmore icon-position-after\">\n                <a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/brasil-tem-grandes-chances-de-liderar-transicao-energetica-global-ate-2045-segundo-marcio-venicio\/\" class=\"guten-readmore\">Read More<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i><\/a>\n            <\/div>\n            <\/div><\/div>\n                <\/article><article class=\"guten-post post-1794 post type-post status-publish format-standard has-post-thumbnail hentry category-entrevistas category-noticias\">\n                    <div class=\"guten-thumb\"><a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/as-5-licoes-de-grzegorz-drozd-para-se-ter-um-planejamento-estrategico-de-sucesso\/\"><div class=\"thumbnail-container\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"720\" src=\"https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/06\/5-passos-para-se-ter-um-planejamento-estrategico-de-Sucesso.jpeg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/06\/5-passos-para-se-ter-um-planejamento-estrategico-de-Sucesso.jpeg 1280w, https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/06\/5-passos-para-se-ter-um-planejamento-estrategico-de-Sucesso-300x169.jpeg 300w, https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/06\/5-passos-para-se-ter-um-planejamento-estrategico-de-Sucesso-1024x576.jpeg 1024w, https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/06\/5-passos-para-se-ter-um-planejamento-estrategico-de-Sucesso-768x432.jpeg 768w, https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/06\/5-passos-para-se-ter-um-planejamento-estrategico-de-Sucesso-18x10.jpeg 18w\" sizes=\"auto, 100vw\" \/>\n\t\t\t<div class=\"guten-overlay\"><\/div>\n        <\/div><\/a><\/div>\n                    <div class=\"guten-postblock-content\"><h3 class=\"guten-post-title\"><a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/as-5-licoes-de-grzegorz-drozd-para-se-ter-um-planejamento-estrategico-de-sucesso\/\">As 5 li\u00e7\u00f5es de Grzegorz Drozd para se ter um planejamento estrat\u00e9gico de sucesso<\/a><\/h3>\n                <div class=\"guten-post-meta\"><div class=\"guten-meta-author icon-position-before\"><i aria-hidden=\"true\" class=\"fas fa-user\"><\/i><span class=\"by\">by<\/span> <a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/author\/claudinei\/\">Claudinei Abreu<\/a><\/div><div class=\"guten-meta-date icon-position-before\"><i aria-hidden=\"true\" class=\"fas fa-clock\"><\/i>06\/06\/2025<\/div><\/div><div class=\"guten-post-excerpt\"><p>As 5 li\u00e7\u00f5es de Grzegorz Drozd para se ter um planejamento estrat\u00e9gico de sucesso Grzegorz Drozd, Vice-Chefe da Unidade, Comiss\u00e3o&#8230;<\/p><\/div>\n            <div class=\"guten-post-meta-bottom\">\n                <div class=\"guten-meta-readmore icon-position-after\">\n                <a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/as-5-licoes-de-grzegorz-drozd-para-se-ter-um-planejamento-estrategico-de-sucesso\/\" class=\"guten-readmore\">Read More<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i><\/a>\n            <\/div>\n            <\/div><\/div>\n                <\/article><article class=\"guten-post post-1797 post type-post status-publish format-standard has-post-thumbnail hentry category-entrevistas category-noticias\">\n                    <div class=\"guten-thumb\"><a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/entenda-o-que-e-o-horizon-scanning-e-sua-importancia-para-planejar-o-futuro\/\"><div class=\"thumbnail-container\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"1116\" height=\"638\" src=\"https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/06\/Horizon-Scanning.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/06\/Horizon-Scanning.png 1116w, https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/06\/Horizon-Scanning-300x172.png 300w, https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/06\/Horizon-Scanning-1024x585.png 1024w, https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/06\/Horizon-Scanning-768x439.png 768w, https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/06\/Horizon-Scanning-18x10.png 18w\" sizes=\"auto, 100vw\" \/>\n\t\t\t<div class=\"guten-overlay\"><\/div>\n        <\/div><\/a><\/div>\n                    <div class=\"guten-postblock-content\"><h3 class=\"guten-post-title\"><a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/entenda-o-que-e-o-horizon-scanning-e-sua-importancia-para-planejar-o-futuro\/\">Entenda o que \u00e9 o horizon scanning e sua import\u00e2ncia para planejar o futuro<\/a><\/h3>\n                <div class=\"guten-post-meta\"><div class=\"guten-meta-author icon-position-before\"><i aria-hidden=\"true\" class=\"fas fa-user\"><\/i><span class=\"by\">by<\/span> <a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/author\/claudinei\/\">Claudinei Abreu<\/a><\/div><div class=\"guten-meta-date icon-position-before\"><i aria-hidden=\"true\" class=\"fas fa-clock\"><\/i>06\/06\/2025<\/div><\/div><div class=\"guten-post-excerpt\"><p>Entenda o que \u00e9 o horizon scanning e sua import\u00e2ncia para planejar o futuro Horizon scanning \u00e9 uma metodologia que&#8230;<\/p><\/div>\n            <div class=\"guten-post-meta-bottom\">\n                <div class=\"guten-meta-readmore icon-position-after\">\n                <a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/entenda-o-que-e-o-horizon-scanning-e-sua-importancia-para-planejar-o-futuro\/\" class=\"guten-readmore\">Read More<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i><\/a>\n            <\/div>\n            <\/div><\/div>\n                <\/article><article class=\"guten-post post-1790 post type-post status-publish format-standard has-post-thumbnail hentry category-entrevistas category-noticias\">\n                    <div class=\"guten-thumb\"><a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/e-um-titulo-que-muitas-vezes-vem-com-desafios-e-desinformacao-afirma-thor-gustavson-sobre-ser-futurista\/\"><div class=\"thumbnail-container\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"661\" height=\"360\" src=\"https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/06\/futurismo.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/06\/futurismo.jpg 661w, https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/06\/futurismo-300x163.jpg 300w, https:\/\/socialport.com.br\/wp-content\/uploads\/2025\/06\/futurismo-18x10.jpg 18w\" sizes=\"auto, 100vw\" \/>\n\t\t\t<div class=\"guten-overlay\"><\/div>\n        <\/div><\/a><\/div>\n                    <div class=\"guten-postblock-content\"><h3 class=\"guten-post-title\"><a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/e-um-titulo-que-muitas-vezes-vem-com-desafios-e-desinformacao-afirma-thor-gustavson-sobre-ser-futurista\/\">&#8216;\u00c9 um t\u00edtulo que muitas vezes vem com desafios e desinforma\u00e7\u00e3o&#8217;, afirma Thor Gustavson sobre ser Futurista<\/a><\/h3>\n                <div class=\"guten-post-meta\"><div class=\"guten-meta-author icon-position-before\"><i aria-hidden=\"true\" class=\"fas fa-user\"><\/i><span class=\"by\">by<\/span> <a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/author\/claudinei\/\">Claudinei Abreu<\/a><\/div><div class=\"guten-meta-date icon-position-before\"><i aria-hidden=\"true\" class=\"fas fa-clock\"><\/i>06\/06\/2025<\/div><\/div><div class=\"guten-post-excerpt\"><p>&#8216;\u00c9 um t\u00edtulo que muitas vezes vem com desafios e desinforma\u00e7\u00e3o&#8217;, afirma Thor Gustavson sobre ser Futurista Thor \u00e9 futurista&#8230;<\/p><\/div>\n            <div class=\"guten-post-meta-bottom\">\n                <div class=\"guten-meta-readmore icon-position-after\">\n                <a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/e-um-titulo-que-muitas-vezes-vem-com-desafios-e-desinformacao-afirma-thor-gustavson-sobre-ser-futurista\/\" class=\"guten-readmore\">Read More<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i><\/a>\n            <\/div>\n            <\/div><\/div>\n                <\/article><article class=\"guten-post post-1678 post type-post status-publish format-standard has-post-thumbnail hentry category-entrevistas\">\n                    <div class=\"guten-thumb\"><a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/entrevista-livia-abreu-consumidor-do-futuro\/\"><div class=\"thumbnail-container\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"954\" src=\"https:\/\/socialport.com.br\/wp-content\/uploads\/2023\/07\/future-consumer-2.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/socialport.com.br\/wp-content\/uploads\/2023\/07\/future-consumer-2.jpg 1600w, https:\/\/socialport.com.br\/wp-content\/uploads\/2023\/07\/future-consumer-2-300x179.jpg 300w, https:\/\/socialport.com.br\/wp-content\/uploads\/2023\/07\/future-consumer-2-1024x611.jpg 1024w, https:\/\/socialport.com.br\/wp-content\/uploads\/2023\/07\/future-consumer-2-768x458.jpg 768w, https:\/\/socialport.com.br\/wp-content\/uploads\/2023\/07\/future-consumer-2-1536x916.jpg 1536w\" sizes=\"auto, 100vw\" \/>\n\t\t\t<div class=\"guten-overlay\"><\/div>\n        <\/div><\/a><\/div>\n                    <div class=\"guten-postblock-content\"><h3 class=\"guten-post-title\"><a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/entrevista-livia-abreu-consumidor-do-futuro\/\">Entrevista L\u00edvia Abreu &#8211; Consumidor do futuro<\/a><\/h3>\n                <div class=\"guten-post-meta\"><div class=\"guten-meta-author icon-position-before\"><i aria-hidden=\"true\" class=\"fas fa-user\"><\/i><span class=\"by\">by<\/span> <a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/author\/jotatri\/\">Jo\u00e3o Menezes<\/a><\/div><div class=\"guten-meta-date icon-position-before\"><i aria-hidden=\"true\" class=\"fas fa-clock\"><\/i>21\/07\/2023<\/div><\/div><div class=\"guten-post-excerpt\"><p>A digitaliza\u00e7\u00e3o, o envelhecimento da popula\u00e7\u00e3o e preocupa\u00e7\u00e3o com o meio ambiente, s\u00e3o algumas das tend\u00eancias que prometem provocar grandes&#8230;<\/p><\/div>\n            <div class=\"guten-post-meta-bottom\">\n                <div class=\"guten-meta-readmore icon-position-after\">\n                <a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/entrevista-livia-abreu-consumidor-do-futuro\/\" class=\"guten-readmore\">Read More<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i><\/a>\n            <\/div>\n            <\/div><\/div>\n                <\/article><article class=\"guten-post post-1668 post type-post status-publish format-standard has-post-thumbnail hentry category-entrevistas category-noticias\">\n                    <div class=\"guten-thumb\"><a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/entrevista-marcello-pio-e-anaely-machado-futuro-do-trabalho\/\"><div class=\"thumbnail-container\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1057\" src=\"https:\/\/socialport.com.br\/wp-content\/uploads\/2023\/07\/futureofwork.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/socialport.com.br\/wp-content\/uploads\/2023\/07\/futureofwork.jpg 1600w, https:\/\/socialport.com.br\/wp-content\/uploads\/2023\/07\/futureofwork-300x198.jpg 300w, https:\/\/socialport.com.br\/wp-content\/uploads\/2023\/07\/futureofwork-1024x676.jpg 1024w, https:\/\/socialport.com.br\/wp-content\/uploads\/2023\/07\/futureofwork-768x507.jpg 768w, https:\/\/socialport.com.br\/wp-content\/uploads\/2023\/07\/futureofwork-1536x1015.jpg 1536w\" sizes=\"auto, 100vw\" \/>\n\t\t\t<div class=\"guten-overlay\"><\/div>\n        <\/div><\/a><\/div>\n                    <div class=\"guten-postblock-content\"><h3 class=\"guten-post-title\"><a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/entrevista-marcello-pio-e-anaely-machado-futuro-do-trabalho\/\">Entrevista Marcello Pio e Anaely Machado &#8211; Futuro do Trabalho<\/a><\/h3>\n                <div class=\"guten-post-meta\"><div class=\"guten-meta-author icon-position-before\"><i aria-hidden=\"true\" class=\"fas fa-user\"><\/i><span class=\"by\">by<\/span> <a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/author\/jotatri\/\">Jo\u00e3o Menezes<\/a><\/div><div class=\"guten-meta-date icon-position-before\"><i aria-hidden=\"true\" class=\"fas fa-clock\"><\/i>20\/07\/2023<\/div><\/div><div class=\"guten-post-excerpt\"><p>O futuro do mercado de trabalho \u00e9 o tema de um dos cap\u00edtulos do livro que ser\u00e1 lan\u00e7ado no Rio&#8230;<\/p><\/div>\n            <div class=\"guten-post-meta-bottom\">\n                <div class=\"guten-meta-readmore icon-position-after\">\n                <a href=\"javascript:void(0);\" data-href=\"https:\/\/socialport.com.br\/en\/entrevista-marcello-pio-e-anaely-machado-futuro-do-trabalho\/\" class=\"guten-readmore\">Read More<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i><\/a>\n            <\/div>\n            <\/div><\/div>\n                <\/article>\n        <\/div>\n        <\/div><div class=\"guten-block-pagination guten-align\"><div class=\"guten-block-loadmore icon-position-before\"><span data-load=\"Load More\" data-loading=\"Loading...\"> Load More<\/span><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Entrevistas<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2364","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/socialport.com.br\/en\/wp-json\/wp\/v2\/pages\/2364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/socialport.com.br\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/socialport.com.br\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/socialport.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/socialport.com.br\/en\/wp-json\/wp\/v2\/comments?post=2364"}],"version-history":[{"count":10,"href":"https:\/\/socialport.com.br\/en\/wp-json\/wp\/v2\/pages\/2364\/revisions"}],"predecessor-version":[{"id":2582,"href":"https:\/\/socialport.com.br\/en\/wp-json\/wp\/v2\/pages\/2364\/revisions\/2582"}],"wp:attachment":[{"href":"https:\/\/socialport.com.br\/en\/wp-json\/wp\/v2\/media?parent=2364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}